{"id":574,"date":"2018-05-05T16:51:41","date_gmt":"2018-05-05T16:51:41","guid":{"rendered":"http:\/\/bastop.com\/?p=574"},"modified":"2024-03-25T14:00:46","modified_gmt":"2024-03-25T14:00:46","slug":"574-2","status":"publish","type":"post","link":"https:\/\/bastop.com\/es\/574-2\/","title":{"rendered":"(Portugu\u00eas do Brasil) Meu primeiro Lollapalooza in Buenos Aires"},"content":{"rendered":"Um dos meus sonhos era assistir um show da Lana del Rey um dia, n\u00e3o achei que o realizaria t\u00e3o cedo quando estava morando na minha cidade no Brasil, mas gracas a ter vindo morar a Buenos Aires pude ent\u00e3o o realizar. Foi algo de \u00faltima hora, comprar o ingresso, achar companhia, seria minha primeira vez indo ao Lollapaloza, foi uma experi\u00eancia \u00fanica e incr\u00edvel, n\u00e3o sei descrever como foi quando a Lana apareceu e come\u00e7ou a cantar, durante todo o show eu estava em um estado de transe, s\u00f3 foi um pouco ruim por eu ser baixinha haha mas mesmo assim consegui v\u00ea-la um pouco.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-575 aligncenter\" src=\"http:\/\/bastop.com\/wp-content\/uploads\/2018\/05\/29356636_2036164536627193_837262583976536463_n-300x296.jpg\" alt=\"29356636_2036164536627193_837262583976536463_n\" width=\"300\" height=\"296\" srcset=\"https:\/\/bastop.com\/wp-content\/uploads\/2018\/05\/29356636_2036164536627193_837262583976536463_n-300x296.jpg 300w, https:\/\/bastop.com\/wp-content\/uploads\/2018\/05\/29356636_2036164536627193_837262583976536463_n.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-576 aligncenter\" src=\"http:\/\/bastop.com\/wp-content\/uploads\/2018\/05\/31531638_2057269874516659_5642560886242541568_n-300x225.jpg\" alt=\"31531638_2057269874516659_5642560886242541568_n\" width=\"300\" height=\"225\" srcset=\"https:\/\/bastop.com\/wp-content\/uploads\/2018\/05\/31531638_2057269874516659_5642560886242541568_n-300x225.jpg 300w, https:\/\/bastop.com\/wp-content\/uploads\/2018\/05\/31531638_2057269874516659_5642560886242541568_n-768x576.jpg 768w, https:\/\/bastop.com\/wp-content\/uploads\/2018\/05\/31531638_2057269874516659_5642560886242541568_n.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Buenos Aires \u00e9 uma cidade grande, cheia de oportunidades, cheia de encantos, onde os sonhos acontecem e a felicidade se encontra em cada esquina, nas pequenas coisas, sensa\u00e7\u00f5es e prazeres. Foi uma decis\u00e3o muito dif\u00edcil e que requeria muita coragem vir morar aqui mas o resultado valeu mais a pena que tudo, cada dia eu confirmo isso. Te amo Buenos Aires a cada dia declaro meu amor por voc\u00ea, nas ruas, nos caf\u00e9s, nos meus lugares preferidos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-577 aligncenter\" src=\"http:\/\/bastop.com\/wp-content\/uploads\/2018\/05\/unnamed-1-300x296.jpg\" alt=\"unnamed (1)\" width=\"300\" height=\"296\" srcset=\"https:\/\/bastop.com\/wp-content\/uploads\/2018\/05\/unnamed-1-300x296.jpg 300w, https:\/\/bastop.com\/wp-content\/uploads\/2018\/05\/unnamed-1.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>POR: MARIANNE","protected":false},"excerpt":{"rendered":"<p>Um dos meus sonhos era assistir um show da Lana del Rey um dia, n\u00e3o achei que o realizaria t\u00e3o cedo quando estava morando na minha cidade no Brasil, mas gracas a<a class=\"moretag\" href=\"https:\/\/bastop.com\/es\/574-2\/\">Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":576,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"_joinchat":[],"footnotes":""},"categories":[11,10,34],"tags":[],"class_list":["post-574","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-bastop","category-buenos-aires","category-things-to-do-in-buenos-aires","post_format-post-format-gallery"],"_links":{"self":[{"href":"https:\/\/bastop.com\/es\/wp-json\/wp\/v2\/posts\/574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bastop.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bastop.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bastop.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bastop.com\/es\/wp-json\/wp\/v2\/comments?post=574"}],"version-history":[{"count":4,"href":"https:\/\/bastop.com\/es\/wp-json\/wp\/v2\/posts\/574\/revisions"}],"predecessor-version":[{"id":591,"href":"https:\/\/bastop.com\/es\/wp-json\/wp\/v2\/posts\/574\/revisions\/591"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bastop.com\/es\/wp-json\/wp\/v2\/media\/576"}],"wp:attachment":[{"href":"https:\/\/bastop.com\/es\/wp-json\/wp\/v2\/media?parent=574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bastop.com\/es\/wp-json\/wp\/v2\/categories?post=574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bastop.com\/es\/wp-json\/wp\/v2\/tags?post=574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}