{"id":612,"date":"2018-06-02T19:02:02","date_gmt":"2018-06-02T19:02:02","guid":{"rendered":"http:\/\/bastop.com\/?p=612"},"modified":"2024-03-25T14:00:46","modified_gmt":"2024-03-25T14:00:46","slug":"dichos-de-calle-florida","status":"publish","type":"post","link":"https:\/\/bastop.com\/es\/dichos-de-calle-florida\/","title":{"rendered":"(English) Dichos de Calle florida"},"content":{"rendered":"\u00bbCambio d\u00f3lar,cambio d\u00f3lar.\u00bb<\/p>\n<p>\u00abEl mejor cuero de la ciudad\u00bb<\/p>\n<p>\u00abTour a Uruguay, a Tigres.\u00bb<\/p>\n<p>Calle florida,\u00a0La calle Florida, uno de los \u00edconos de la capital argentina, tuvo su tiro de gracia con las recesiones en la Argentina y Brasil. El corredor comercial fue castigado por la ca\u00edda del consumo local y tur\u00edstico. El escenario, dicen los expertos, es similar al de la crisis de 2002, por la cantidad de carteles de inmobiliarias que asoman en las fachadas y el tiempo que tardan en quitarse.","protected":false},"excerpt":{"rendered":"<p>\u00bbCambio d\u00f3lar,cambio d\u00f3lar.\u00bb \u00abEl mejor cuero de la ciudad\u00bb \u00abTour a Uruguay, a Tigres.\u00bb Calle florida,\u00a0La calle Florida, uno de los \u00edconos de la capital argentina, tuvo su tiro de gracia con<a class=\"moretag\" href=\"https:\/\/bastop.com\/es\/dichos-de-calle-florida\/\">Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":613,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-612","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/bastop.com\/es\/wp-json\/wp\/v2\/posts\/612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bastop.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bastop.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bastop.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bastop.com\/es\/wp-json\/wp\/v2\/comments?post=612"}],"version-history":[{"count":1,"href":"https:\/\/bastop.com\/es\/wp-json\/wp\/v2\/posts\/612\/revisions"}],"predecessor-version":[{"id":614,"href":"https:\/\/bastop.com\/es\/wp-json\/wp\/v2\/posts\/612\/revisions\/614"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bastop.com\/es\/wp-json\/wp\/v2\/media\/613"}],"wp:attachment":[{"href":"https:\/\/bastop.com\/es\/wp-json\/wp\/v2\/media?parent=612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bastop.com\/es\/wp-json\/wp\/v2\/categories?post=612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bastop.com\/es\/wp-json\/wp\/v2\/tags?post=612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}