{"id":676,"date":"2018-09-18T22:45:09","date_gmt":"2018-09-18T22:45:09","guid":{"rendered":"http:\/\/bastop.com\/?p=676"},"modified":"2024-03-25T14:00:45","modified_gmt":"2024-03-25T14:00:45","slug":"espanol-buenos-aires-capital-de-estudiantes","status":"publish","type":"post","link":"https:\/\/bastop.com\/es\/espanol-buenos-aires-capital-de-estudiantes\/","title":{"rendered":"Buenos Aires: Capital de Estudiantes"},"content":{"rendered":"<strong>uenos Aires<\/strong>\u00a0no es solamente visitada por turistas que vienen a admirar sus arquitecturas y a respirar toda su cultura, tambi\u00e9n vienen muchos\u00a0<strong>estudiantes extranjeros<\/strong>\u00a0a realizar alg\u00fan tipo de\u00a0<strong>intercambio,<em>workshop<\/em>\u00a0o especializaci\u00f3n<\/strong>\u00a0que complemente sus estudios, o a\u00a0<strong>estudiar espa\u00f1ol<\/strong>. Aqu\u00ed te presentamos algunas de las propuestas que tienen las\u00a0<strong>universidades<\/strong>\u00a0ubicadas en la\u00a0<strong>Ciudad de Buenos Aires<\/strong>\u00a0para los estudiantes extranjeros.<\/p>\n<p>La\u00a0<strong><a class=\"external\" href=\"http:\/\/www.palermo.edu\/estudiantes_internacionales\/index.html\" target=\"_blank\" rel=\"nofollow noopener\">Universidad de Palermo (UP)<\/a><\/strong>\u00a0tiene tres programas dirigidos a alumnos for\u00e1neos: dos apuntados a aprender a hablar espa\u00f1ol o perfeccionarlo (Spanish as a Second Language Program y Latin America Cultural Identity Program), y uno puntualmente dedicado a la formaci\u00f3n profesional relacionada a la carrera (Custom Made Programs for Universities), en el cual se podr\u00e1n cursar materias a elecci\u00f3n junto con los alumnos locales.<\/p>\n<p>La\u00a0<strong><a class=\"external\" href=\"http:\/\/www.udesa.edu.ar\/Study-Abroad\" target=\"_blank\" rel=\"nofollow noopener\">Universidad de San Andr\u00e9s<\/a><\/strong>\u00a0tiene dos propuestas acorde al tiempo de estad\u00eda en el pa\u00eds: la primera consiste en un programa que abarca de un semestre a un a\u00f1o, en el cual el alumno puede anotarse a cursos relacionados a las areas de econom\u00eda, administraci\u00f3n, relaciones internacionales, ciencias pol\u00edticas, educaci\u00f3n, comunicaci\u00f3n y derecho. La segunda es un programa de corta duraci\u00f3n, inferior a los seis meses, en el que se ofrecen tem\u00e1ticas variadas y un curso intensivo de espa\u00f1ol a lo largo de cinco semanas.<\/p>\n<p>La\u00a0<strong><a class=\"external\" href=\"http:\/\/www.ub.edu.ar\/\" target=\"_blank\" rel=\"nofollow noopener\">Universidad de Belgrano (UB)<\/a><\/strong>\u00a0ofrece cuatro programas de intercambio para alumnos extranjeros. El primero refiere al espa\u00f1ol como lengua extranjera. El segundo es un Programa de Estudios Latinoamericanos que consiste en doce cursos que abarcan las areas de historia, literatura y arte argentino y latinomericano con una duraci\u00f3n de quince semanas. El tercero es el programa Un Semestre en Argentina que permite al alumno\u00a0<a href=\"https:\/\/www.4rentargentina.com\/blog\/es\/wp-content\/uploads\/UBA-economicas.jpg\" rel=\"prettyPhoto[gallery-SeAJ]\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-750\" title=\"UBA\" src=\"https:\/\/www.4rentargentina.com\/blog\/es\/wp-content\/uploads\/UBA-economicas.jpg\" alt=\"\" width=\"260\" height=\"195\" \/><\/a>estudiar cualquier curso regular de las carreras de la universidad. Por \u00faltimo, el programa Argentina: Historia y Sociedad consiste en un curso dictado en ingl\u00e9s sobre historia, econom\u00eda, ciencias pol\u00edticas y literatura argentina.<\/p>\n<p>La\u00a0<strong>Universidad de Buenos Aires (UBA)<\/strong>\u00a0permite al alumno ingresar en la instituci\u00f3n de mayor prestigio en el pa\u00eds de manera gratuita. Para ello, se encuentra disponible toda la oferta acad\u00e9mica, como tambi\u00e9n la posibilidad de hacer alg\u00fan semestre en alguna de las diversas facultades presentando la documentaci\u00f3n y consultando en la sede donde se encuentra el curso de inter\u00e9s.<\/p>\n<p>La gran mayor\u00eda de estas universidades se encuentran ubicadas en las zonas de mayor actividad de la ciudad, donde el extranjero tambi\u00e9n podr\u00e1 conocer mejor la diversidad de Buenos Aires. Para ello, nada mejor que hospedarse en un\u00a0<strong>departamento amueblado para alquiler temporario<\/strong>\u00a0en la zona de\u00a0<strong>Palermo y Belgrano.<\/strong><\/p>\n<p>https:\/\/turismojoven.buenosaires.gob.ar\/ (Aprovecha toda la programaci\u00f3n de <strong>Study Buenos Aires<\/strong>","protected":false},"excerpt":{"rendered":"<p>uenos Aires\u00a0no es solamente visitada por turistas que vienen a admirar sus arquitecturas y a respirar toda su cultura, tambi\u00e9n vienen muchos\u00a0estudiantes extranjeros\u00a0a realizar alg\u00fan tipo de\u00a0intercambio,workshop\u00a0o especializaci\u00f3n\u00a0que complemente sus estudios, o<a class=\"moretag\" href=\"https:\/\/bastop.com\/es\/espanol-buenos-aires-capital-de-estudiantes\/\">Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":677,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-676","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/bastop.com\/es\/wp-json\/wp\/v2\/posts\/676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bastop.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bastop.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bastop.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bastop.com\/es\/wp-json\/wp\/v2\/comments?post=676"}],"version-history":[{"count":2,"href":"https:\/\/bastop.com\/es\/wp-json\/wp\/v2\/posts\/676\/revisions"}],"predecessor-version":[{"id":877,"href":"https:\/\/bastop.com\/es\/wp-json\/wp\/v2\/posts\/676\/revisions\/877"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bastop.com\/es\/wp-json\/wp\/v2\/media\/677"}],"wp:attachment":[{"href":"https:\/\/bastop.com\/es\/wp-json\/wp\/v2\/media?parent=676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bastop.com\/es\/wp-json\/wp\/v2\/categories?post=676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bastop.com\/es\/wp-json\/wp\/v2\/tags?post=676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}